{"id":12748,"date":"2026-03-24T12:00:09","date_gmt":"2026-03-24T11:00:09","guid":{"rendered":"https:\/\/www.colours.cz\/place\/gong-stage-maly-sal\/"},"modified":"2026-07-15T01:59:15","modified_gmt":"2026-07-14T23:59:15","slug":"gong-stage-maly-sal","status":"publish","type":"place","link":"https:\/\/www.colours.cz\/en\/place\/gong-stage-maly-sal\/","title":{"rendered":"GONG STAGE &#8211; MAL\u00dd S\u00c1L"},"menu_order":8,"template":"","place-category":[422],"class_list":["post-12748","place","type-place","status-publish","hentry","place-category-stage-en"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.3.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>GONG STAGE - MAL\u00dd S\u00c1L - Colours of Ostrava<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"GONG STAGE - MAL\u00dd S\u00c1L - Colours of Ostrava\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.colours.cz\/en\/place\/gong-stage-maly-sal\/\" \/>\n<meta property=\"og:site_name\" content=\"Colours of Ostrava\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-14T23:59:15+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"GONG STAGE - MAL\u00dd S\u00c1L - Colours of Ostrava","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"GONG STAGE - MAL\u00dd S\u00c1L - Colours of Ostrava","og_url":"https:\/\/www.colours.cz\/en\/place\/gong-stage-maly-sal\/","og_site_name":"Colours of Ostrava","article_modified_time":"2026-07-14T23:59:15+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.colours.cz\/en\/place\/gong-stage-maly-sal\/","url":"https:\/\/www.colours.cz\/en\/place\/gong-stage-maly-sal\/","name":"GONG STAGE - MAL\u00dd S\u00c1L - Colours of Ostrava","isPartOf":{"@id":"https:\/\/www.colours.cz\/en\/#website"},"datePublished":"2026-03-24T11:00:09+00:00","dateModified":"2026-07-14T23:59:15+00:00","breadcrumb":{"@id":"https:\/\/www.colours.cz\/en\/place\/gong-stage-maly-sal\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.colours.cz\/en\/place\/gong-stage-maly-sal\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.colours.cz\/en\/place\/gong-stage-maly-sal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Dom\u016f","item":"https:\/\/www.colours.cz\/en\/"},{"@type":"ListItem","position":2,"name":"GONG STAGE &#8211; MAL\u00dd S\u00c1L"}]},{"@type":"WebSite","@id":"https:\/\/www.colours.cz\/en\/#website","url":"https:\/\/www.colours.cz\/en\/","name":"Colours of Ostrava","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.colours.cz\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"place-params-color":"pink","place-params-description":"A theater scene that transcends the boundaries of its genre \u2014 small-form theater, stand-up comedy, and popular discussion shows.","place-params-use-custom-color":"0","place-params-custom-color":"#ffec00ff","place-params-icon":"ea68","place-gps-latitude":"49.81916373177772","place-gps-longitude":"18.279851676946436","place-gallery-items-ids":[{"place-items-image-id":"18713","place-items-title":"","place-items-description":""}],"place_custom_color":null,"_links":{"self":[{"href":"https:\/\/www.colours.cz\/en\/wp-json\/wp\/v2\/place\/12748","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.colours.cz\/en\/wp-json\/wp\/v2\/place"}],"about":[{"href":"https:\/\/www.colours.cz\/en\/wp-json\/wp\/v2\/types\/place"}],"wp:attachment":[{"href":"https:\/\/www.colours.cz\/en\/wp-json\/wp\/v2\/media?parent=12748"}],"wp:term":[{"taxonomy":"place-category","embeddable":true,"href":"https:\/\/www.colours.cz\/en\/wp-json\/wp\/v2\/place-category?post=12748"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}